{"id":36721,"date":"2026-07-13T11:04:23","date_gmt":"2026-07-13T09:04:23","guid":{"rendered":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/"},"modified":"2026-07-14T14:04:07","modified_gmt":"2026-07-14T12:04:07","slug":"responsable-de-boutique-aix-en-provence-cdi-h-f","status":"publish","type":"jobs_cpt","link":"https:\/\/www.smcp.com\/fr\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/","title":{"rendered":"Responsable de boutique &#8211; Aix en Provence &#8211; CDI H\/F"},"parent":0,"template":"","class_list":["post-36721","jobs_cpt","type-jobs_cpt","status-publish","hentry","brand_taxo-fursac","jobtitle_taxo-retail-sales","contract_type_taxo-cdi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Responsable de boutique - Aix en Provence - CDI H\/F - SMCP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Responsable de boutique - Aix en Provence - CDI H\/F - SMCP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/\" \/>\n<meta property=\"og:site_name\" content=\"SMCP\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T12:04:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/\",\"url\":\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/\",\"name\":\"Responsable de boutique - Aix en Provence - CDI H\/F - SMCP\",\"isPartOf\":{\"@id\":\"https:\/\/www.smcp.com\/en\/#website\"},\"datePublished\":\"2026-07-13T09:04:23+00:00\",\"dateModified\":\"2026-07-14T12:04:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.smcp.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Responsable de boutique &#8211; Aix en Provence &#8211; CDI H\/F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.smcp.com\/en\/#website\",\"url\":\"https:\/\/www.smcp.com\/en\/\",\"name\":\"SMCP\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.smcp.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Responsable de boutique - Aix en Provence - CDI H\/F - SMCP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/","og_locale":"fr_FR","og_type":"article","og_title":"Responsable de boutique - Aix en Provence - CDI H\/F - SMCP","og_url":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/","og_site_name":"SMCP","article_modified_time":"2026-07-14T12:04:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/","url":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/","name":"Responsable de boutique - Aix en Provence - CDI H\/F - SMCP","isPartOf":{"@id":"https:\/\/www.smcp.com\/en\/#website"},"datePublished":"2026-07-13T09:04:23+00:00","dateModified":"2026-07-14T12:04:07+00:00","breadcrumb":{"@id":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.smcp.com\/offre-emploi\/responsable-de-boutique-aix-en-provence-cdi-h-f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smcp.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Responsable de boutique &#8211; Aix en Provence &#8211; CDI H\/F"}]},{"@type":"WebSite","@id":"https:\/\/www.smcp.com\/en\/#website","url":"https:\/\/www.smcp.com\/en\/","name":"SMCP","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smcp.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/jobs_cpt\/36721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/jobs_cpt"}],"about":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/types\/jobs_cpt"}],"wp:attachment":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/media?parent=36721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}