{"id":36391,"date":"2026-06-17T18:02:54","date_gmt":"2026-06-17T16:02:54","guid":{"rendered":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/"},"modified":"2026-09-02T14:03:06","modified_gmt":"2026-09-02T12:03:06","slug":"sales-assistant-20hrs-dusseldorf-m-w-d","status":"publish","type":"jobs_cpt","link":"https:\/\/www.smcp.com\/fr\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/","title":{"rendered":"Sales Assistant &#8211; 20hrs &#8211; D\u00fcsseldorf &#8211; M\/W\/D"},"parent":0,"template":"","class_list":["post-36391","jobs_cpt","type-jobs_cpt","status-publish","hentry","brand_taxo-sandro","jobtitle_taxo-retail-sales","contract_type_taxo-cdd"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sales Assistant - 20hrs - D\u00fcsseldorf - M\/W\/D - SMCP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sales Assistant - 20hrs - D\u00fcsseldorf - M\/W\/D - SMCP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/\" \/>\n<meta property=\"og:site_name\" content=\"SMCP\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T12:03:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/\",\"url\":\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/\",\"name\":\"Sales Assistant - 20hrs - D\u00fcsseldorf - M\/W\/D - SMCP\",\"isPartOf\":{\"@id\":\"https:\/\/www.smcp.com\/en\/#website\"},\"datePublished\":\"2026-06-17T16:02:54+00:00\",\"dateModified\":\"2026-09-02T12:03:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.smcp.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sales Assistant &#8211; 20hrs &#8211; D\u00fcsseldorf &#8211; M\/W\/D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.smcp.com\/en\/#website\",\"url\":\"https:\/\/www.smcp.com\/en\/\",\"name\":\"SMCP\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.smcp.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sales Assistant - 20hrs - D\u00fcsseldorf - M\/W\/D - SMCP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/","og_locale":"fr_FR","og_type":"article","og_title":"Sales Assistant - 20hrs - D\u00fcsseldorf - M\/W\/D - SMCP","og_url":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/","og_site_name":"SMCP","article_modified_time":"2026-09-02T12:03:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/","url":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/","name":"Sales Assistant - 20hrs - D\u00fcsseldorf - M\/W\/D - SMCP","isPartOf":{"@id":"https:\/\/www.smcp.com\/en\/#website"},"datePublished":"2026-06-17T16:02:54+00:00","dateModified":"2026-09-02T12:03:06+00:00","breadcrumb":{"@id":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.smcp.com\/offre-emploi\/sales-assistant-20hrs-dusseldorf-m-w-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smcp.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sales Assistant &#8211; 20hrs &#8211; D\u00fcsseldorf &#8211; M\/W\/D"}]},{"@type":"WebSite","@id":"https:\/\/www.smcp.com\/en\/#website","url":"https:\/\/www.smcp.com\/en\/","name":"SMCP","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smcp.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/jobs_cpt\/36391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/jobs_cpt"}],"about":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/types\/jobs_cpt"}],"wp:attachment":[{"href":"https:\/\/www.smcp.com\/fr\/wp-json\/wp\/v2\/media?parent=36391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}